{"id":5461,"date":"2025-03-10T10:07:23","date_gmt":"2022-12-05T18:03:18","guid":{"rendered":"https:\/\/decoplanta.com\/?post_type=product&#038;p=5461"},"modified":"2022-12-05T19:06:18","modified_gmt":"2022-12-05T18:06:18","slug":"feto-uv-90cm-para-exterior","status":"publish","type":"product","link":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/","title":{"rendered":"FETO UV"},"content":{"rendered":"<p><span data-sheets-value=\"{\" data-sheets-userformat=\"{\">Planta de FETO artificial para uso externo, 90 cm de altura. Com protec\u00e7\u00e3o UV, pode viver ao ar livre e n\u00e3o se desvanece, tornando-o o complemento perfeito para o seu jardim. Incrivelmente bonito, acrescenta cor e um toque natural a qualquer espa\u00e7o. Com delicadas folhas verdes para adicionar alguma textura. Inclui un vaso de flores b\u00e1sico.<\/span><\/p>\n<p>Planta de origem tropical, de pa\u00edses como o Uruguai, Brasil e Paraguai. \u00c9 um feto muito utilizada para decorar o <a href=\"https:\/\/decoplanta.com\/etiqueta-producto\/helecho-de-exterior\/\">exterior<\/a> da casa num vaso ou num vaso para pendurar. \u00c9 uma planta de interior num local h\u00famido e iluminado. Tamb\u00e9m pode ser colocado ao ar livre \u00e0 sombra ou semi-sombra, onde n\u00e3o recebe sol directo.<\/p>\n<h3>Como o Feto UV artificial \u00e9 diferente de outros fetos?<\/h3>\n<p>Culantrillo (Adiantum cuneatum) \u00e9 um feto pertencente \u00e0 fam\u00edlia Pteridaceae. \u00c9 um herb\u00e1ceo perene at\u00e9 50 cm de altura, com um longo rizoma rastejante. Geralmente cresce em paredes rochosas de fontes e lugares sombrios. Al\u00e9m disso, s\u00e3o plantas que carecem de flores, frutos e sementes, pelo que a sua especialidade s\u00e3o as suas folhas.<\/p>\n<p>Los <a href=\"https:\/\/es.wikipedia.org\/wiki\/Filicopsida#:~:text=Los%20helechos%20son%20plantas%20sin,Los%20helechos%20son%20notables%20por%3A&amp;text=Sus%20hojas%20(frondes).\">fetos<\/a> s\u00e3o plantas sem flores nem sementes, pertencentes ao grupo das Pterid\u00f3fitas. Eles se reproduzem por meio de esporos, que precisam da presen\u00e7a de \u00e1gua para completar seu ciclo biol\u00f3gico.<\/p>\n<h3>Planta artificial para decorar o seu jardim ou terra\u00e7o<\/h3>\n<p>As nossas plantas artificiais na sec\u00e7\u00e3o &#8220;Mini Decora\u00e7\u00e3o&#8221; ir\u00e3o mudar o aspecto do seu espa\u00e7o de trabalho. Aqui encontrar\u00e1 diferentes tipos de plantas artificiais que caber\u00e3o perfeitamente no seu escrit\u00f3rio. Temos uma grande variedade de pequenas plantas artificiais com as quais podemos completar espa\u00e7os com um detalhe vegetal. As nossas plantas artificiais s\u00e3o tamb\u00e9m adequadas para qualquer estilo de decora\u00e7\u00e3o. De estilos cl\u00e1ssicos, r\u00fasticos, modernos ou mesmo minimalistas para aqueles que adoram decora\u00e7\u00e3o. As nossas pequenas plantas artificiais s\u00e3o perfeitas para tornar o seu neg\u00f3cio num local atractivo para os clientes. Um pequeno detalhe como este \u00e9 muito importante para criar uma boa impress\u00e3o. Naturalmente, as nossas pe\u00e7as centrais de mesa s\u00e3o o elemento de que necessita para mudar o aspecto do seu neg\u00f3cio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feto artificial para uso externo, 90 cm de altura. Com prote\u00e7\u00e3o UV, pode viver ao ar livre e n\u00e3o desbota, tornando-se o complemento perfeito para o seu jardim. Incrivelmente bonito, adiciona cor e uma sensa\u00e7\u00e3o natural a qualquer espa\u00e7o. Com delicadas folhas verdes para adicionar alguma textura. Inclui vaso b\u00e1sico.<\/p>\n<table>\n<tbody>\n<tr>\n<td><strong>REF<\/strong><\/td>\n<td>Altura<\/td>\n<\/tr>\n<tr>\n<td><strong>430308<\/strong><\/td>\n<td>90 cm<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"featured_media":5429,"template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"product_brand":[],"product_cat":[394],"product_tag":[407,412,422],"class_list":["post-5461","product","type-product","status-publish","has-post-thumbnail","product_cat-plantas-ao-ar-livre-artificiais","product_tag-planta-artificial-com-protecao-uv","product_tag-feto-artificial-ao-ar-livre","product_tag-planta-tropical","","woocommerce-text-align-center","woocommerce-image-align-center","do-quantity-buttons","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feto artificial para exterior com prote\u00e7\u00e3o UV- Alto realismo<\/title>\n<meta name=\"description\" content=\"Feto artificial com 90 cm de altura. Com prote\u00e7\u00e3o UV, para exteriores e n\u00e3o desbota, tornando-se o complemento perfeito no seu jardi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feto artificial para exterior com prote\u00e7\u00e3o UV- Alto realismo\" \/>\n<meta property=\"og:description\" content=\"Feto artificial com 90 cm de altura. Com prote\u00e7\u00e3o UV, para exteriores e n\u00e3o desbota, tornando-se o complemento perfeito no seu jardi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/\" \/>\n<meta property=\"og:site_name\" content=\"Plantas y \u00e1rboles artificiales de Alto Realismo\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-05T18:06:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/decoplanta.com\/wp-content\/uploads\/2022\/12\/430308-HELECHO_UV-90cm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2300\" \/>\n\t<meta property=\"og:image:height\" content=\"2300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/\",\"url\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/\",\"name\":\"Feto artificial para exterior com prote\u00e7\u00e3o UV- Alto realismo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/decoplanta.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/430308-HELECHO_UV-90cm.jpg\",\"datePublished\":\"2022-12-05T18:03:18+00:00\",\"dateModified\":\"2022-12-05T18:06:18+00:00\",\"description\":\"Feto artificial com 90 cm de altura. Com prote\u00e7\u00e3o UV, para exteriores e n\u00e3o desbota, tornando-se o complemento perfeito no seu jardi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/#primaryimage\",\"url\":\"https:\\\/\\\/decoplanta.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/430308-HELECHO_UV-90cm.jpg\",\"contentUrl\":\"https:\\\/\\\/decoplanta.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/430308-HELECHO_UV-90cm.jpg\",\"width\":2300,\"height\":2300,\"caption\":\"Helecho artificial para exterior de 90 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/plantas-ao-ar-livre-artificiais\\\/feto-uv-90cm-para-exterior\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Priv\u00e9\u00a0: Tienda\",\"item\":\"https:\\\/\\\/decoplanta.com\\\/?page_id=377\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FETO UV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/\",\"name\":\"Plantas y \u00e1rboles artificiales de Alto Realismo\",\"description\":\"Proveedor de Plantas artificiales para estudios de Arquitectura, Interiorismo, Paisajismo, Escenograf\u00eda, Tiendas de Decoraci\u00f3n Florister\u00edas y Mobiliario\",\"publisher\":{\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/#organization\",\"name\":\"Plantas y \u00e1rboles artificiales de Alto Realismo\",\"url\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/decoplanta.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/decoplanta-logo2020.svg\",\"contentUrl\":\"https:\\\/\\\/decoplanta.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/decoplanta-logo2020.svg\",\"width\":500,\"height\":500,\"caption\":\"Plantas y \u00e1rboles artificiales de Alto Realismo\"},\"image\":{\"@id\":\"https:\\\/\\\/decoplanta.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feto artificial para exterior com prote\u00e7\u00e3o UV- Alto realismo","description":"Feto artificial com 90 cm de altura. Com prote\u00e7\u00e3o UV, para exteriores e n\u00e3o desbota, tornando-se o complemento perfeito no seu jardi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/","og_locale":"pt_PT","og_type":"article","og_title":"Feto artificial para exterior com prote\u00e7\u00e3o UV- Alto realismo","og_description":"Feto artificial com 90 cm de altura. Com prote\u00e7\u00e3o UV, para exteriores e n\u00e3o desbota, tornando-se o complemento perfeito no seu jardi","og_url":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/","og_site_name":"Plantas y \u00e1rboles artificiales de Alto Realismo","article_modified_time":"2022-12-05T18:06:18+00:00","og_image":[{"width":2300,"height":2300,"url":"https:\/\/decoplanta.com\/wp-content\/uploads\/2022\/12\/430308-HELECHO_UV-90cm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/","url":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/","name":"Feto artificial para exterior com prote\u00e7\u00e3o UV- Alto realismo","isPartOf":{"@id":"https:\/\/decoplanta.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/#primaryimage"},"image":{"@id":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/#primaryimage"},"thumbnailUrl":"https:\/\/decoplanta.com\/wp-content\/uploads\/2022\/12\/430308-HELECHO_UV-90cm.jpg","datePublished":"2022-12-05T18:03:18+00:00","dateModified":"2022-12-05T18:06:18+00:00","description":"Feto artificial com 90 cm de altura. Com prote\u00e7\u00e3o UV, para exteriores e n\u00e3o desbota, tornando-se o complemento perfeito no seu jardi","breadcrumb":{"@id":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/#primaryimage","url":"https:\/\/decoplanta.com\/wp-content\/uploads\/2022\/12\/430308-HELECHO_UV-90cm.jpg","contentUrl":"https:\/\/decoplanta.com\/wp-content\/uploads\/2022\/12\/430308-HELECHO_UV-90cm.jpg","width":2300,"height":2300,"caption":"Helecho artificial para exterior de 90 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/decoplanta.com\/pt-pt\/plantas-ao-ar-livre-artificiais\/feto-uv-90cm-para-exterior\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/decoplanta.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Priv\u00e9\u00a0: Tienda","item":"https:\/\/decoplanta.com\/?page_id=377"},{"@type":"ListItem","position":3,"name":"FETO UV"}]},{"@type":"WebSite","@id":"https:\/\/decoplanta.com\/pt-pt\/#website","url":"https:\/\/decoplanta.com\/pt-pt\/","name":"Plantas y \u00e1rboles artificiales de Alto Realismo","description":"Proveedor de Plantas artificiales para estudios de Arquitectura, Interiorismo, Paisajismo, Escenograf\u00eda, Tiendas de Decoraci\u00f3n Florister\u00edas y Mobiliario","publisher":{"@id":"https:\/\/decoplanta.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/decoplanta.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/decoplanta.com\/pt-pt\/#organization","name":"Plantas y \u00e1rboles artificiales de Alto Realismo","url":"https:\/\/decoplanta.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/decoplanta.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/decoplanta.com\/wp-content\/uploads\/2021\/02\/decoplanta-logo2020.svg","contentUrl":"https:\/\/decoplanta.com\/wp-content\/uploads\/2021\/02\/decoplanta-logo2020.svg","width":500,"height":500,"caption":"Plantas y \u00e1rboles artificiales de Alto Realismo"},"image":{"@id":"https:\/\/decoplanta.com\/pt-pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/product\/5461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/product\/5461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/media\/5429"}],"wp:attachment":[{"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=5461"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/product_brand?post=5461"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/product_cat?post=5461"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/decoplanta.com\/pt-pt\/wp-json\/wp\/v2\/product_tag?post=5461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}